{"id":53153,"date":"2023-12-12T14:24:05","date_gmt":"2023-12-12T13:24:05","guid":{"rendered":"https:\/\/dokterswacht.mindd.dev\/?page_id=53153"},"modified":"2025-03-17T12:39:05","modified_gmt":"2025-03-17T11:39:05","slug":"jouw-ervaring","status":"publish","type":"page","link":"https:\/\/dokterswacht.nl\/pl\/jouw-ervaring\/","title":{"rendered":"Hoe heb je Dokterswacht ervaren?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wij doen er alles aan om goede zorg te leveren op een prettige en professionele manier. Toch kan het zijn dat je niet helemaal tevreden bent over de zorg. We horen graag wat jouw ervaring was, zodat we onze zorgverlening kunnen verbeteren. Misschien heb je een suggestie, compliment of wil je een klacht indienen. Vul onderstaand formulier in en we nemen het zo spoedig mogelijk in behandeling.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Wat doen we met jouw inbreng?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Als het gaat om een klacht, neemt onze klachtenfunctionaris contact met je op en probeert samen met jou tot een oplossing te komen.<strong> <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De klachtenfunctionaris:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>bespreekt met jou de klacht en geeft informatie en advies;&nbsp;<\/li>\n\n\n\n<li>bespreekt hoe de klacht het beste kan worden behandeld;&nbsp;<\/li>\n\n\n\n<li>bemiddelt tussen jou en degene over wie je ontevreden bent;&nbsp;<\/li>\n\n\n\n<li>informeert jou over verdere klachtenbehandelingsmogelijkheden als dat nodig is.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Suggesties voor verbetering of complimenten nemen we in behandeling. We geven je een terugkoppeling over wat we er mee hebben gedaan.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jouw inbreng behandelen we vertrouwelijk. We hebben geheimhoudingsplicht en gaan zorgvuldig om met jouw privacy. Als je jouw ervaring met ons deelt, geef je daarmee toestemming dat de klachtenfunctionaris je dossier in kan zien, als dat nodig is voor de afhandeling. In onze <a href=\"https:\/\/dokterswacht.nl\/wp-content\/uploads\/sites\/107\/2025\/03\/2024-03-Klachtenregeling-Dokterszorg-Friesland.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">klachtenregeling<\/a> staat uitgebreid beschreven hoe we met klachten omgaan.\u00a0<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Deel hier jouw ervaring met Dokterswacht<\/h2>\n\n\n\n<iframe src=\"https:\/\/formulieren.qlink.biz\/form-dokterswacht-klacht.aspx\" width=\"100%\" height=\"800\" style=\"border: none\">\n   \n<\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">Lukt het niet om het formulier te verzenden, stuur dan een e-mail naar&nbsp;<a href=\"mailto:klachten@dokterswacht.nl\" target=\"_blank\" rel=\"noreferrer noopener\">klachten@dokterswacht.nl<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wij doen er alles aan om goede zorg te leveren op een prettige en professionele manier. Toch kan het zijn dat je niet helemaal tevreden bent over de zorg. We horen graag wat jouw ervaring was, zodat we onze zorgverlening kunnen verbeteren. Misschien heb je een suggestie, compliment of wil je een klacht indienen. Vul [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"class_list":["post-53153","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoe heb je Dokterswacht ervaren? - Dokterswacht Friesland - Polski<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoe heb je Dokterswacht ervaren? - Dokterswacht Friesland - Polski\" \/>\n<meta property=\"og:description\" content=\"Wij doen er alles aan om goede zorg te leveren op een prettige en professionele manier. Toch kan het zijn dat je niet helemaal tevreden bent over de zorg. We horen graag wat jouw ervaring was, zodat we onze zorgverlening kunnen verbeteren. Misschien heb je een suggestie, compliment of wil je een klacht indienen. Vul [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dokterswacht.nl\/pl\/jouw-ervaring\/\" \/>\n<meta property=\"og:site_name\" content=\"Dokterswacht Friesland - Polski\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-17T11:39:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/jouw-ervaring\\\/\",\"url\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/jouw-ervaring\\\/\",\"name\":\"Hoe heb je Dokterswacht ervaren? - Dokterswacht Friesland - Polski\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/#website\"},\"datePublished\":\"2023-12-12T13:24:05+00:00\",\"dateModified\":\"2025-03-17T11:39:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/jouw-ervaring\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/jouw-ervaring\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/jouw-ervaring\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoe heb je Dokterswacht ervaren?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/\",\"name\":\"Dokterswacht Friesland - Polski\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dokterswacht.nl\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoe heb je Dokterswacht ervaren? - Dokterswacht Friesland - Polski","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pl_PL","og_type":"article","og_title":"Hoe heb je Dokterswacht ervaren? - Dokterswacht Friesland - Polski","og_description":"Wij doen er alles aan om goede zorg te leveren op een prettige en professionele manier. Toch kan het zijn dat je niet helemaal tevreden bent over de zorg. We horen graag wat jouw ervaring was, zodat we onze zorgverlening kunnen verbeteren. Misschien heb je een suggestie, compliment of wil je een klacht indienen. Vul [&hellip;]","og_url":"https:\/\/dokterswacht.nl\/pl\/jouw-ervaring\/","og_site_name":"Dokterswacht Friesland - Polski","article_modified_time":"2025-03-17T11:39:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dokterswacht.nl\/pl\/jouw-ervaring\/","url":"https:\/\/dokterswacht.nl\/pl\/jouw-ervaring\/","name":"Hoe heb je Dokterswacht ervaren? - Dokterswacht Friesland - Polski","isPartOf":{"@id":"https:\/\/dokterswacht.nl\/pl\/#website"},"datePublished":"2023-12-12T13:24:05+00:00","dateModified":"2025-03-17T11:39:05+00:00","breadcrumb":{"@id":"https:\/\/dokterswacht.nl\/pl\/jouw-ervaring\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dokterswacht.nl\/pl\/jouw-ervaring\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dokterswacht.nl\/pl\/jouw-ervaring\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dokterswacht.nl\/pl\/"},{"@type":"ListItem","position":2,"name":"Hoe heb je Dokterswacht ervaren?"}]},{"@type":"WebSite","@id":"https:\/\/dokterswacht.nl\/pl\/#website","url":"https:\/\/dokterswacht.nl\/pl\/","name":"Dokterswacht Friesland - Polski","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dokterswacht.nl\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/dokterswacht.nl\/pl\/wp-json\/wp\/v2\/pages\/53153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dokterswacht.nl\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dokterswacht.nl\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dokterswacht.nl\/pl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dokterswacht.nl\/pl\/wp-json\/wp\/v2\/comments?post=53153"}],"version-history":[{"count":14,"href":"https:\/\/dokterswacht.nl\/pl\/wp-json\/wp\/v2\/pages\/53153\/revisions"}],"predecessor-version":[{"id":54588,"href":"https:\/\/dokterswacht.nl\/pl\/wp-json\/wp\/v2\/pages\/53153\/revisions\/54588"}],"wp:attachment":[{"href":"https:\/\/dokterswacht.nl\/pl\/wp-json\/wp\/v2\/media?parent=53153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}